{"id":390,"date":"2025-05-04T10:27:26","date_gmt":"2025-05-04T10:27:26","guid":{"rendered":"https:\/\/sailistanbul.com\/blog\/?page_id=390"},"modified":"2025-08-09T12:06:43","modified_gmt":"2025-08-09T12:06:43","slug":"sailistanbul-blog-2","status":"publish","type":"page","link":"https:\/\/gezelim.me\/yat\/blog\/","title":{"rendered":"Gezelim.me Yat \u2013 \u0130stanbul\u2019da Yat Kiralama, Bo\u011faz Turlar\u0131 ve Teknede Ya\u015fam Rehberi"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":61,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-390","page","type-page","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/gezelim.me\/yat\/blog\/wp-json\/wp\/v2\/pages\/390","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gezelim.me\/yat\/blog\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/gezelim.me\/yat\/blog\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/gezelim.me\/yat\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gezelim.me\/yat\/blog\/wp-json\/wp\/v2\/comments?post=390"}],"version-history":[{"count":3,"href":"https:\/\/gezelim.me\/yat\/blog\/wp-json\/wp\/v2\/pages\/390\/revisions"}],"predecessor-version":[{"id":714,"href":"https:\/\/gezelim.me\/yat\/blog\/wp-json\/wp\/v2\/pages\/390\/revisions\/714"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gezelim.me\/yat\/blog\/wp-json\/wp\/v2\/media\/61"}],"wp:attachment":[{"href":"https:\/\/gezelim.me\/yat\/blog\/wp-json\/wp\/v2\/media?parent=390"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}